{"id":4410,"date":"2021-03-20T12:59:43","date_gmt":"2021-03-20T11:59:43","guid":{"rendered":"https:\/\/www.concreteinvesting.com\/?p=4410"},"modified":"2022-12-20T11:40:53","modified_gmt":"2022-12-20T11:40:53","slug":"abba-38-milano","status":"publish","type":"post","link":"https:\/\/www.concreteinvesting.com\/blog\/progetti-immobiliari\/abba-38-milano","title":{"rendered":"Abba 38: i dettagli del progetto immobiliare"},"content":{"rendered":"<p>Il progetto prevede la demolizione e la ricostruzione dell\u2019edificio preesistente, che comprender\u00e0 14 appartamenti con ampi spazi di pertinenza, balconi loggiati e giardini privati.<\/p>\n<p>L\u2019edificio sorger\u00e0 in zona Dergano, quartiere storicamente residenziale di Milano ben collegato, a cavallo tra la Bovisa e Farini.<\/p>\n<h2>Il progetto immobiliare<\/h2>\n<p>Si \u00e8 conclusa con successo l&#8217;offerta di <a href=\"https:\/\/www.concreteinvesting.com\/blog\/progetti-immobiliari\/abba-38-crowdfunding\" target=\"_blank\" rel=\"noopener\">equity crowdfunding per Abba 38<\/a>, il progetto proposto sulla piattaforma Concrete Investing a fine febbraio. Il progetto prevede la demolizione dell\u2019edificio preesistente e la sua ricostruzione in un unico corpo di 4 piani fuori terra, in cui verranno realizzate 14 unit\u00e0 abitative, e 1 piano interrato, con 10 box e 4 posti auto. Gli appartamenti, forniti di ampi spazi di pertinenza, balconi loggiati e giardini privati, saranno di varie tipologie:<\/p>\n<ul>\n<li>5 bilocali;<\/li>\n<li>3 trilocali;<\/li>\n<li>6 quadrilocali;<\/li>\n<li>2 sottotetti.<\/li>\n<\/ul>\n<p>Tutti gli appartamenti sono progettati con cura nei dettagli, nelle soluzioni materiche e nell&#8217;ottimizzazione degli spazi. L\u2019attivit\u00e0 commerciale \u00e8 gi\u00e0 stata avviata e, ad oggi, risulta gi\u00e0 venduto circa il 50% delle unit\u00e0 disponibili. Visto il grande interesse mostrato e la velocit\u00e0 di vendita, si prevede il completamento delle vendite entro la conclusione del cantiere.<\/p>\n<p>Dergano, la zona in cui sorger\u00e0 l\u2019edificio, \u00e8 storicamente residenziale con una forte connotazione di quartiere. Si trova a cavallo della Bovisa, interessata da un\u2019importante valorizzazione trainata dalla presenza del Politecnico di Milano, e Farini, area chiave nella riqualificazione strategica degli scali milanesi. L\u2019area, inoltre, \u00e8 servita da una fitta rete di mezzi di superficie oltre che dalla fermata della M3 Dergano, distante solo 500 metri.<\/p>\n<p>L\u2019intero progetto ha gi\u00e0 ricevuto parere favorevole dalla commissione paesaggistica di Milano e le pratiche edilizie sono state depositate a luglio 2020, mentre il rilascio del permesso per costruire \u00e8 previsto entro aprile 2021, mese in cui inizieranno le demolizioni dell\u2019attuale manufatto. Scavo ed edificazione si concluderanno presumibilmente entro la fine del 2022.<\/p>\n<h2>Sponsor e partner dell\u2019operazione<\/h2>\n<p>Come in ogni operazione promossa dalla nostra piattaforma di crowdfunding immobiliare, anche il Progetto Immobiliare Abba 38 a Milano vede la partecipazione di esperti e professionisti di lunga data. Ecco i partners dell\u2019operazione:<\/p>\n<ul>\n<li>la famiglia Monzani: attiva in operazioni immobiliari da pi\u00f9 di 20 anni, si \u00e8 occupata dell\u2019attivit\u00e0 di sviluppo dell&#8217;operazione;<\/li>\n<li>l\u2019Ing. Simone Dominioni: titolare di uno studio ingegneria e progettista in diversi progetti immobiliari a Milano, ha firmato il progetto architettonico;<\/li>\n<li>AbitareCo: agenzia specializzata nella commercializzazione di nuove costruzioni, attiva a Milano da pi\u00f9 di vent&#8217;anni, si occupa delle attivit\u00e0 di vendita;<\/li>\n<li>il banco BPM garantisce il supporto finanziario, tramite la concessione di un mutuo fondiario erogabile a stato avanzamento lavori per un importo fino a 2.900.000 euro.<\/li>\n<\/ul>\n<p>Per ricevere aggiornamenti sulle altre campagne di equity crowdfunding immobiliare promosse da Concrete Investing e accedere al materiale informativo di ciascuna operazione disponibile, \u00e8 sufficiente registrarsi gratuitamente sul nostro portale con il proprio indirizzo mail.<\/p>\n<p style=\"text-align: center; font-size: 20px;\">\n","protected":false},"excerpt":{"rendered":"<p>Il progetto prevede la demolizione e la ricostruzione dell\u2019edificio preesistente, che comprender\u00e0 14 appartamenti con ampi spazi di pertinenza, balconi loggiati e giardini privati. L\u2019edificio sorger\u00e0 in zona Dergano, quartiere storicamente residenziale di Milano ben collegato, a cavallo tra la Bovisa e Farini. Il progetto immobiliare Si \u00e8 conclusa con successo l&#8217;offerta di equity crowdfunding [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4513,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"_links":{"self":[{"href":"https:\/\/www.concreteinvesting.com\/blog\/wp-json\/wp\/v2\/posts\/4410"}],"collection":[{"href":"https:\/\/www.concreteinvesting.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.concreteinvesting.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.concreteinvesting.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.concreteinvesting.com\/blog\/wp-json\/wp\/v2\/comments?post=4410"}],"version-history":[{"count":3,"href":"https:\/\/www.concreteinvesting.com\/blog\/wp-json\/wp\/v2\/posts\/4410\/revisions"}],"predecessor-version":[{"id":5852,"href":"https:\/\/www.concreteinvesting.com\/blog\/wp-json\/wp\/v2\/posts\/4410\/revisions\/5852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.concreteinvesting.com\/blog\/wp-json\/wp\/v2\/media\/4513"}],"wp:attachment":[{"href":"https:\/\/www.concreteinvesting.com\/blog\/wp-json\/wp\/v2\/media?parent=4410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.concreteinvesting.com\/blog\/wp-json\/wp\/v2\/categories?post=4410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.concreteinvesting.com\/blog\/wp-json\/wp\/v2\/tags?post=4410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}